{"id":498059,"date":"2026-09-02T10:43:23","date_gmt":"2026-09-02T08:43:23","guid":{"rendered":"urn:newsml:dpa.com:20090101:260902-930-620404"},"modified":"2026-09-02T11:11:29","modified_gmt":"2026-09-02T09:11:29","slug":"radsport-star-lipowitz-meldet-sich-zurueck-jetzt-winkt-sogar-die-wm","status":"publish","type":"sport-news","link":"https:\/\/www.tipico.de\/wett-tipps\/sport-news\/radsport-star-lipowitz-meldet-sich-zurueck-jetzt-winkt-sogar-die-wm","title":{"rendered":"Radsport-Star Lipowitz meldet sich zur\u00fcck &#8211; jetzt winkt sogar die WM"},"content":{"rendered":"<p>Deutschlands Radsport-Star Florian Lipowitz kehrt nach seinem schweren Sturz bei der Tour de France in der kommenden Woche ins Renngeschehen zur\u00fcck. Der 25-J\u00e4hrige startet am 9. September beim Giro della Toscana, im Anschluss k\u00f6nnte Lipowitz drei weitere italienische Eintagesrennen binnen vier Tagen bestreiten. Die Entscheidung dar\u00fcber soll erst nach dem Comeback-Rennen fallen.<\/p>\n<h2>Lipowitz: WM-Teilnahme in Montreal wird ernsthafte Option<\/h2>\n<p>Eine ernsthafte Option ist nun die Teilnahme an der Stra\u00dfenrad-Weltmeisterschaft in Montreal Ende des Monats. Mit 3800 H\u00f6henmetern auf 273,7 Kilometern ist das Profil nicht herausragend schwer, kommt Lipowitz mit seinen Kletterqualit\u00e4ten allerdings entgegen. Der fast sichere Ausfall von Tadej Pogacar d\u00fcrfte Lipowitz&#8216; Chancen auf eine Medaille erh\u00f6hen. Der slowenische Titelverteidiger war bei der Spanien-Rundfahrt schwer gest\u00fcrzt und erst am Montag am gebrochenen Schl\u00fcsselbein operiert worden.<\/p>\n<h2>Rennh\u00e4rte statt Ergebnisse im Blick<\/h2>\n<p>&#8222;Nat\u00fcrlich ist die WM ein Rennen, das mich reizt. Aber f\u00fcr mich ist auch klar: Wenn die Form nicht stimmt, m\u00f6chte ich keinem anderen Fahrer einen Startplatz wegnehmen. Wir haben viele starke deutsche Fahrer, denen der Kurs in Montreal liegt&#8220;, sagte Lipowitz.<\/p>\n<p>Ein Formcheck sollen nun die ersten Rennen werden. &#8222;Ich freue mich vor allem darauf, wieder eine Startnummer anzuziehen und Rennen zu fahren. Nach sieben Wochen ohne Wettkampf kann ich noch nicht genau wissen, wo ich stehe. Genau das wollen wir herausfinden. F\u00fcr mich geht es bei diesen ersten Rennen nicht um ein Ergebnis. Ich m\u00f6chte sehen, wie mein K\u00f6rper auf die Rennbelastung reagiert&#8220;, sagte Lipowitz.<\/p>\n<p>Der geb\u00fcrtige Schwabe war im Einzelzeitfahren der Tour de France nach einem Fahrfehler gest\u00fcrzt und hatte sich das Schl\u00fcsselbein gebrochen. Nach den Eins\u00e4tzen in Italien soll \u00fcber den detaillierten Rennplan bis zum Saisonende beraten werden. Genug Zeit bleibt bis zur WM, um eine gute Form aufzubauen.<\/p>\n<p>(dpa)<\/p>\n<p><a title=\"Folge uns auf Google\" href=\"https:\/\/www.google.com\/preferences\/source?q=tipico.de\" target=\"_blank\" rel=\"noopener\"><picture><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.tipico.de\/wett-tipps\/wp-content\/uploads\/2026\/05\/google_preferred_source_badge_dark_DE@2x.png\" alt=\"Folge uns auf Google\" width=\"338\" height=\"107\" \/><\/picture><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nach sieben Wochen Pause kehrt Florian Lipowitz ins Renngeschehen zur\u00fcck. Wie er die Rennen in Italien als Formtest f\u00fcr die m\u00f6gliche WM-Teilnahme nutzen will.<\/p>\n","protected":false},"author":99,"featured_media":498057,"menu_order":0,"template":"","tags":[10393,10442,10464,10431,10427],"news-category":[2517],"class_list":["post-498059","sport-news","type-sport-news","status-publish","has-post-thumbnail","hentry","tag-deutschland","tag-italien","tag-kanada","tag-radsport","tag-wm","news-category-sport-heute"],"acf":{"live_content":[]},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Tipico Wett Tipps<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:site_name\" content=\"Tipico Wett Tipps\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tipico.de\/wett-tipps\/wp-content\/uploads\/2021\/06\/tipico_icon.png\" \/>\n\t<meta property=\"og:image:width\" content=\"512\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Tipico_de\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":null,\"url\":\"\",\"name\":\"\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tipico.de\\\/wett-tipps\\\/#website\"},\"inLanguage\":\"de\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tipico.de\\\/wett-tipps\\\/#website\",\"url\":\"https:\\\/\\\/www.tipico.de\\\/wett-tipps\\\/\",\"name\":\"Tipico Wett Tipps\",\"description\":\"Wett Tipps heute &amp; aktuelle Sportwetten News\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tipico.de\\\/wett-tipps\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tipico.de\\\/wett-tipps\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.tipico.de\\\/wett-tipps\\\/#organization\",\"name\":\"Tipico\",\"url\":\"https:\\\/\\\/www.tipico.de\\\/wett-tipps\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.tipico.de\\\/wett-tipps\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.tipico.de\\\/wett-tipps\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/www.tipico.de\\\/wett-tipps\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo.svg\",\"width\":\"1024\",\"height\":\"1024\",\"caption\":\"Tipico\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tipico.de\\\/wett-tipps\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/tipico\\\/\",\"https:\\\/\\\/x.com\\\/Tipico_de\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Tipico Wett Tipps","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"de_DE","og_type":"article","og_site_name":"Tipico Wett Tipps","og_image":[{"width":512,"height":512,"url":"https:\/\/www.tipico.de\/wett-tipps\/wp-content\/uploads\/2021\/06\/tipico_icon.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@Tipico_de","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":null,"url":"","name":"","isPartOf":{"@id":"https:\/\/www.tipico.de\/wett-tipps\/#website"},"inLanguage":"de"},{"@type":"WebSite","@id":"https:\/\/www.tipico.de\/wett-tipps\/#website","url":"https:\/\/www.tipico.de\/wett-tipps\/","name":"Tipico Wett Tipps","description":"Wett Tipps heute &amp; aktuelle Sportwetten News","publisher":{"@id":"https:\/\/www.tipico.de\/wett-tipps\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tipico.de\/wett-tipps\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.tipico.de\/wett-tipps\/#organization","name":"Tipico","url":"https:\/\/www.tipico.de\/wett-tipps\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.tipico.de\/wett-tipps\/#\/schema\/logo\/image\/","url":"https:\/\/www.tipico.de\/wett-tipps\/wp-content\/uploads\/2021\/02\/logo.svg","contentUrl":"https:\/\/www.tipico.de\/wett-tipps\/wp-content\/uploads\/2021\/02\/logo.svg","width":"1024","height":"1024","caption":"Tipico"},"image":{"@id":"https:\/\/www.tipico.de\/wett-tipps\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/tipico\/","https:\/\/x.com\/Tipico_de"]}]}},"_links":{"self":[{"href":"https:\/\/www.tipico.de\/wett-tipps\/wp-json\/wp\/v2\/sport-news\/498059"}],"collection":[{"href":"https:\/\/www.tipico.de\/wett-tipps\/wp-json\/wp\/v2\/sport-news"}],"about":[{"href":"https:\/\/www.tipico.de\/wett-tipps\/wp-json\/wp\/v2\/types\/sport-news"}],"author":[{"embeddable":true,"href":"https:\/\/www.tipico.de\/wett-tipps\/wp-json\/wp\/v2\/users\/99"}],"version-history":[{"count":1,"href":"https:\/\/www.tipico.de\/wett-tipps\/wp-json\/wp\/v2\/sport-news\/498059\/revisions"}],"predecessor-version":[{"id":498078,"href":"https:\/\/www.tipico.de\/wett-tipps\/wp-json\/wp\/v2\/sport-news\/498059\/revisions\/498078"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tipico.de\/wett-tipps\/wp-json\/wp\/v2\/media\/498057"}],"wp:attachment":[{"href":"https:\/\/www.tipico.de\/wett-tipps\/wp-json\/wp\/v2\/media?parent=498059"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tipico.de\/wett-tipps\/wp-json\/wp\/v2\/tags?post=498059"},{"taxonomy":"news-category","embeddable":true,"href":"https:\/\/www.tipico.de\/wett-tipps\/wp-json\/wp\/v2\/news-category?post=498059"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}