{"id":482366,"date":"2026-07-15T14:07:43","date_gmt":"2026-07-15T12:07:43","guid":{"rendered":"https:\/\/www.tipico.de\/wett-tipps\/sportwetten-news\/?p=482366"},"modified":"2026-07-15T14:07:43","modified_gmt":"2026-07-15T12:07:43","slug":"fenerbahce-mit-rekordtransfer-top-torjaeger-der-ligue-1-kommt","status":"publish","type":"post","link":"https:\/\/www.tipico.de\/wett-tipps\/sportwetten-news\/fenerbahce-mit-rekordtransfer-top-torjaeger-der-ligue-1-kommt","title":{"rendered":"Fenerbahce mit Rekordtransfer: Top-Torj\u00e4ger der Ligue 1 kommt"},"content":{"rendered":"<p>Fenerbahce News beim <a href=\"https:\/\/www.tipico.de\/wett-tipps\/sportwetten-news\/category\/fussball-heute\">Fu\u00dfball heute<\/a>: Einer der begehrtesten Offensivspieler dieses Sommers hat seine Zukunft gekl\u00e4rt. F\u00fcr eine hohe Abl\u00f6se zieht es den 24-J\u00e4hrigen in die T\u00fcrkei \u2013 und das, obwohl auch ein spanischer Spitzenklub interessiert war. Dessen R\u00fcckzug hatte einen kuriosen Grund.<\/p>\n<h2>Fenerbahce: Greenwood-Deal offiziell<\/h2>\n<p>Wie <strong>Fenerbahce Istanbul<\/strong> offiziell best\u00e4tigte, wechselt <strong>Mason Greenwood<\/strong> von Olympique Marseille an den Bosporus. Laut der Vereinsmitteilung zahlt der t\u00fcrkische Traditionsklub eine <strong>Abl\u00f6se von 39 Millionen Euro<\/strong>, die in drei Raten \u00fcberwiesen wird. Der neue Vertrag des englischen Offensivspielers gilt bis 2030.<\/p>\n<p>F\u00fcr Fenerbahce ist es ein Rekordgesch\u00e4ft: Greenwood wird <strong>der teuerste Zugang der Klubgeschichte<\/strong> und in der <a href=\"https:\/\/www.tipico.de\/wett-tipps\/sueper-lig-tipps\">S\u00fcper Lig<\/a> zum zweitteuersten Transfer \u00fcberhaupt \u2013 nur f\u00fcr Victor Osimhen legte ein Ligakonkurrent einst mehr auf den Tisch. Sein bisheriger Klub Marseille muss zudem einen Teil des Gewinns an Manchester United abgeben, das \u00fcber eine Weiterverkaufsbeteiligung mitverdient.<\/p>\n<h2>Der kuriose R\u00fcckzug von Atletico bei Greenwood<\/h2>\n<p>Fenerbahce war nicht der einzige Interessent. Auch Atletico Madrid besch\u00e4ftigte sich mit einer Verpflichtung, zog sich aber vorzeitig aus den Verhandlungen zur\u00fcck. Laut <em>L&#8217;\u00c9quipe<\/em> st\u00f6rte sich der spanische Klub am Verhalten des Spielers: Greenwood soll zwei Tage lang nicht auf eine Nachricht von Trainer Diego Simeone reagiert haben.<\/p>\n<p>Daneben lagen dem Angreifer auch Angebote aus Saudi-Arabien vor. Am Ende entschied er sich f\u00fcr den Tabellenzweiten der vergangenen t\u00fcrkischen Saison. Die Teilnahme an der <a href=\"https:\/\/www.tipico.de\/wett-tipps\/champions-league-tipps\">Champions League<\/a> ist damit allerdings noch nicht sicher \u2013 Fenerbahce muss den Umweg \u00fcber die zweite Qualifikationsrunde nehmen.<\/p>\n<h2>Fenerbahces Rekordzugang Greenwood: Sportlicher Aufschwung in Frankreich<\/h2>\n<p>Greenwoods Karriere hatte zuletzt wieder deutlich an Fahrt gewonnen. Nach einer Leihe zum FC Getafe wechselte er 2024 f\u00fcr rund 25 Millionen Euro zu Marseille und schlug dort sofort ein: In seiner Deb\u00fctsaison wurde er mit 21 Treffern geteilter Torsch\u00fctzenk\u00f6nig der <a href=\"https:\/\/www.tipico.de\/wett-tipps\/ligue-1-tipps\">Ligue 1<\/a>, in der vergangenen Spielzeit folgten <strong>26 Tore in 45 Partien<\/strong>. Sein Marktwert kletterte in der Folge auf einen Karriereh\u00f6chstwert.<\/p>\n<p>Zuvor war seine Zeit bei seinem Jugendklub Manchester United nach justiziellen Vorw\u00fcrfen unsch\u00f6n geendet. Nachdem die Anklage 2023 fallengelassen worden war, kam er nicht mehr f\u00fcr die Red Devils zum Einsatz. Beim neuen Klub sorgte seine Verpflichtung nicht \u00fcberall f\u00fcr Zustimmung: Auch bei Konkurrent AS Rom hatte es zuletzt Interesse gegeben, dort formierte sich unter Anh\u00e4ngern jedoch Widerstand gegen einen m\u00f6glichen Transfer.<\/p>\n<p><a title=\"Folge uns auf Google\" href=\"https:\/\/www.google.com\/preferences\/source?q=tipico.de\" target=\"_blank\" rel=\"noopener\"><picture><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.tipico.de\/wett-tipps\/wp-content\/uploads\/2026\/05\/google_preferred_source_badge_dark_DE@2x.png\" alt=\"Folge uns auf Google\" width=\"338\" height=\"107\" \/> <\/picture><\/a><\/p>\n<p><em>Hinsichtlich der <a href=\"https:\/\/www.tipico.de\/wett-tipps\/sportwetten-tipps\">Sportwetten Tipps<\/a> findest du detaillierte <a href=\"https:\/\/www.tipico.de\/wett-tipps\/fussball-vorhersage\">Fu\u00dfball-Tipps<\/a> und passende <a href=\"https:\/\/sports.tipico.de\/v1\/tpapi\/ctfes\/redirect?campaignId=a4krlorh&amp;target=https:\/\/sports.tipico.de\/de\/heute\/fussball\">Fu\u00dfball-Wetten<\/a> bei Tipico. \u00dcbrigens: Hast du schon von <a href=\"https:\/\/www.tipico.de\/wett-tipps\/tipico-million\">Tipico Million<\/a> geh\u00f6rt? Weitere Fu\u00dfball News gibt es bei unseren <a href=\"https:\/\/www.tipico.de\/wett-tipps\/sport-news\">Sport News<\/a>, unseren Content mit <a href=\"https:\/\/sports.tipico.de\/v1\/tpapi\/ctfes\/redirect?campaignId=a4krlorh&amp;target=https:\/\/sports.tipico.de\/de\">Sportwetten<\/a>-Bezug liefern wir dir bei den <a href=\"https:\/\/www.tipico.de\/wett-tipps\/sportwetten-news\">Sportwetten News<\/a>.<\/em><\/p>\n<h3>Fu\u00dfball Wett Tipps heute: Tipps &amp; Quoten<\/h3>\n\n\t        <div class=\"b-table--tips\">\n            <div class=\"table-body\">\n\t\t\t\t\t\t\t\t\t                    <div class=\"table-cell\">\n                        <div class=\"table-cell__info\">\n                            <h4 class=\"table-cell__title\">KF Malisheva - KF Vllaznia<\/h4>\n                            <small class=\"table-cell__date\">15.07.2026, 16:30 Uhr - Stadiumi Zahir Pajaziti<\/small>\n                        <\/div>\n\n                        <a href=\"https:\/\/sports.tipico.de\/v1\/tpapi\/ctfes\/redirect?campaignId=8cmx3rpu&#038;target=https:\/\/sports.tipico.de\/de\/alle\/fussball\/europa-conference-league%20\" target=\"_blank\" class=\"table-cell__tip btn btn-odds\">\n                            <div class=\"tip-caption\">\n\t\t\t\t\t\t\t\tTipp 1                            <\/div>\n                            <div class=\"tip-value\">\n\t\t\t\t\t\t\t\t1,65                                <script type=\"application\/ld+json\">\n                                    {\n                                        \"@context\": \"https:\/\/schema.org\",\n                                        \"@type\": \"SportsEvent\",\n                                        \"name\": \"KF Malisheva - KF Vllaznia\",\n                                        \"location\": {\n                                        \"@type\": \"Place\",\n                                        \"name\": \"Stadiumi Zahir Pajaziti\",\n                                        \"address\": \"Stadiumi Zahir Pajaziti\"\n                                        },\n                                        \"startDate\": \"2026-07-15T16:30:00+00:00\"\n                                    }\n\n\n                                <\/script>\n                            <\/div>\n                        <\/a>\n\n                    <\/div>\n\t\t\t\t\t\t\t\t\t                    <div class=\"table-cell\">\n                        <div class=\"table-cell__info\">\n                            <h4 class=\"table-cell__title\">CS Universitatea Craiova - Maxline Vitebsk<\/h4>\n                            <small class=\"table-cell__date\">15.07.2026, 19:30 Uhr - Stadionul Ion Oblemenco<\/small>\n                        <\/div>\n\n                        <a href=\"https:\/\/sports.tipico.de\/v1\/tpapi\/ctfes\/redirect?campaignId=sro0vsqm&#038;target=https:\/\/sports.tipico.de\/de\/alle\/fussball\/champions-league\" target=\"_blank\" class=\"table-cell__tip btn btn-odds\">\n                            <div class=\"tip-caption\">\n\t\t\t\t\t\t\t\t\u00dcber 2,5                            <\/div>\n                            <div class=\"tip-value\">\n\t\t\t\t\t\t\t\t1,50                                <script type=\"application\/ld+json\">\n                                    {\n                                        \"@context\": \"https:\/\/schema.org\",\n                                        \"@type\": \"SportsEvent\",\n                                        \"name\": \"CS Universitatea Craiova - Maxline Vitebsk\",\n                                        \"location\": {\n                                        \"@type\": \"Place\",\n                                        \"name\": \"Stadionul Ion Oblemenco\",\n                                        \"address\": \"Stadionul Ion Oblemenco\"\n                                        },\n                                        \"startDate\": \"2026-07-15T19:30:00+00:00\"\n                                    }\n\n\n                                <\/script>\n                            <\/div>\n                        <\/a>\n\n                    <\/div>\n\t\t\t\t\t\t\t\t\t                    <div class=\"table-cell\">\n                        <div class=\"table-cell__info\">\n                            <h4 class=\"table-cell__title\">Atert Bissen - KI Klaksvik<\/h4>\n                            <small class=\"table-cell__date\">15.07.2026, 20:15 Uhr - Stade de Luxembourg<\/small>\n                        <\/div>\n\n                        <a href=\"https:\/\/sports.tipico.de\/v1\/tpapi\/ctfes\/redirect?campaignId=sro0vsqm&#038;target=https:\/\/sports.tipico.de\/de\/alle\/fussball\/champions-league\" target=\"_blank\" class=\"table-cell__tip btn btn-odds\">\n                            <div class=\"tip-caption\">\n\t\t\t\t\t\t\t\tHead-to-Head Tipp 2                            <\/div>\n                            <div class=\"tip-value\">\n\t\t\t\t\t\t\t\t1,85                                <script type=\"application\/ld+json\">\n                                    {\n                                        \"@context\": \"https:\/\/schema.org\",\n                                        \"@type\": \"SportsEvent\",\n                                        \"name\": \"Atert Bissen - KI Klaksvik\",\n                                        \"location\": {\n                                        \"@type\": \"Place\",\n                                        \"name\": \"Stade de Luxembourg\",\n                                        \"address\": \"Stade de Luxembourg\"\n                                        },\n                                        \"startDate\": \"2026-07-15T20:15:00+00:00\"\n                                    }\n\n\n                                <\/script>\n                            <\/div>\n                        <\/a>\n\n                    <\/div>\n\t\t\t\t\t\t\t\t\t                    <div class=\"table-cell\">\n                        <div class=\"table-cell__info\">\n                            <h4 class=\"table-cell__title\">FK Decic Tuzi - FK Liepaja<\/h4>\n                            <small class=\"table-cell__date\">15.07.2026, 20:30 Uhr - Tusko<\/small>\n                        <\/div>\n\n                        <a href=\"https:\/\/sports.tipico.de\/v1\/tpapi\/ctfes\/redirect?campaignId=8cmx3rpu&#038;target=https:\/\/sports.tipico.de\/de\/alle\/fussball\/europa-conference-league\" target=\"_blank\" class=\"table-cell__tip btn btn-odds\">\n                            <div class=\"tip-caption\">\n\t\t\t\t\t\t\t\tUnter 2,5                            <\/div>\n                            <div class=\"tip-value\">\n\t\t\t\t\t\t\t\t1,75                                <script type=\"application\/ld+json\">\n                                    {\n                                        \"@context\": \"https:\/\/schema.org\",\n                                        \"@type\": \"SportsEvent\",\n                                        \"name\": \"FK Decic Tuzi - FK Liepaja\",\n                                        \"location\": {\n                                        \"@type\": \"Place\",\n                                        \"name\": \"Tusko\",\n                                        \"address\": \"Tusko\"\n                                        },\n                                        \"startDate\": \"2026-07-15T20:30:00+00:00\"\n                                    }\n\n\n                                <\/script>\n                            <\/div>\n                        <\/a>\n\n                    <\/div>\n\t\t\t\t\t\t\t\t\t                    <div class=\"table-cell\">\n                        <div class=\"table-cell__info\">\n                            <h4 class=\"table-cell__title\"><a href=\"https:\/\/www.tipico.de\/wett-tipps\/sportwetten-news\/england-vs-argentinien-tipp-quoten-prognose-wm-15-07-2026\">England - Argentinien <\/a><\/h4>\n                            <small class=\"table-cell__date\">15.07.2026, 21:00 Uhr - Mercedes-Benz Stadium, Atlanta<\/small>\n                        <\/div>\n\n                        <a href=\"https:\/\/sports.tipico.de\/v1\/tpapi\/ctfes\/redirect?campaignId=s748ndrf&#038;target=https:\/\/sports.tipico.de\/de\/alle\/fussball\/wm-wetten\" target=\"_blank\" class=\"table-cell__tip btn btn-odds\">\n                            <div class=\"tip-caption\">\n\t\t\t\t\t\t\t\t\u00dcber 2,5                            <\/div>\n                            <div class=\"tip-value\">\n\t\t\t\t\t\t\t\t2,35                                <script type=\"application\/ld+json\">\n                                    {\n                                        \"@context\": \"https:\/\/schema.org\",\n                                        \"@type\": \"SportsEvent\",\n                                        \"name\": \"England - Argentinien\",\n                                        \"location\": {\n                                        \"@type\": \"Place\",\n                                        \"name\": \"Mercedes-Benz Stadium, Atlanta\",\n                                        \"address\": \"Mercedes-Benz Stadium, Atlanta\"\n                                        },\n                                        \"startDate\": \"2026-07-15T21:00:00+00:00\"\n                                    }\n\n\n                                <\/script>\n                            <\/div>\n                        <\/a>\n\n                    <\/div>\n\t\t\t\t\t\t\t\t\t                    <div class=\"table-cell\">\n                        <div class=\"table-cell__info\">\n                            <h4 class=\"table-cell__title\">Egnatia Rrogozhine - FC Petrocub<\/h4>\n                            <small class=\"table-cell__date\">15.07.2026, 21:00 Uhr - Demrozi Stadium<\/small>\n                        <\/div>\n\n                        <a href=\"https:\/\/sports.tipico.de\/v1\/tpapi\/ctfes\/redirect?campaignId=sro0vsqm&#038;target=https:\/\/sports.tipico.de\/de\/alle\/fussball\/champions-league\" target=\"_blank\" class=\"table-cell__tip btn btn-odds\">\n                            <div class=\"tip-caption\">\n\t\t\t\t\t\t\t\tTipp 1                            <\/div>\n                            <div class=\"tip-value\">\n\t\t\t\t\t\t\t\t1,65                                <script type=\"application\/ld+json\">\n                                    {\n                                        \"@context\": \"https:\/\/schema.org\",\n                                        \"@type\": \"SportsEvent\",\n                                        \"name\": \"Egnatia Rrogozhine - FC Petrocub\",\n                                        \"location\": {\n                                        \"@type\": \"Place\",\n                                        \"name\": \"Demrozi Stadium\",\n                                        \"address\": \"Demrozi Stadium\"\n                                        },\n                                        \"startDate\": \"2026-07-15T21:00:00+00:00\"\n                                    }\n\n\n                                <\/script>\n                            <\/div>\n                        <\/a>\n\n                    <\/div>\n\t\t\t\t\t\t\t\t\t                    <div class=\"table-cell\">\n                        <div class=\"table-cell__info\">\n                            <h4 class=\"table-cell__title\">FK Sutjeska Niksic - FC Kairat Almaty<\/h4>\n                            <small class=\"table-cell__date\">15.07.2026, 21:00 Uhr - Stadion Gradski<\/small>\n                        <\/div>\n\n                        <a href=\"https:\/\/sports.tipico.de\/v1\/tpapi\/ctfes\/redirect?campaignId=sro0vsqm&#038;target=https:\/\/sports.tipico.de\/de\/alle\/fussball\/champions-league\" target=\"_blank\" class=\"table-cell__tip btn btn-odds\">\n                            <div class=\"tip-caption\">\n\t\t\t\t\t\t\t\tTipp 2                            <\/div>\n                            <div class=\"tip-value\">\n\t\t\t\t\t\t\t\t1,57                                <script type=\"application\/ld+json\">\n                                    {\n                                        \"@context\": \"https:\/\/schema.org\",\n                                        \"@type\": \"SportsEvent\",\n                                        \"name\": \"FK Sutjeska Niksic - FC Kairat Almaty\",\n                                        \"location\": {\n                                        \"@type\": \"Place\",\n                                        \"name\": \"Stadion Gradski\",\n                                        \"address\": \"Stadion Gradski\"\n                                        },\n                                        \"startDate\": \"2026-07-15T21:00:00+00:00\"\n                                    }\n\n\n                                <\/script>\n                            <\/div>\n                        <\/a>\n\n                    <\/div>\n\t\t\t\t            <\/div>\n        <\/div>\n\t\t<small class=\"b-age-notice\">Quoten\u00e4nderungen vorbehalten<\/small>\t\n\n","protected":false},"excerpt":{"rendered":"<p>Fenerbahce News beim Fu\u00dfball heute: Einer der begehrtesten Offensivspieler dieses Sommers hat seine Zukunft gekl\u00e4rt. F\u00fcr eine hohe Abl\u00f6se zieht es den 24-J\u00e4hrigen in die T\u00fcrkei \u2013 und das, obwohl auch ein spanischer Spitzenklub interessiert war. Dessen R\u00fcckzug hatte einen kuriosen Grund. Fenerbahce: Greenwood-Deal offiziell Wie Fenerbahce Istanbul offiziell best\u00e4tigte, wechselt Mason Greenwood von Olympique [&hellip;]<\/p>\n","protected":false},"author":110,"featured_media":263691,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"dw_urn":"","dw_version":0,"dw_version_created":"","dw_updated":"","footnotes":""},"tags":[],"news-category":[2516,2517],"sport-news":[],"class_list":["post-482366","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","news-category-fussball-heute","news-category-sport-heute"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Fenerbahce mit Rekordtransfer: Top-Torj\u00e4ger der Ligue 1 kommt<\/title>\n<meta name=\"description\" content=\"Der franz\u00f6sische Torsch\u00fctzenk\u00f6nig wechselt f\u00fcr 39 Millionen Euro von Marseille zu Fenerbahce \u2013 welche Rekorde der Deal in der T\u00fcrkei bricht.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tipico.de\/wett-tipps\/sportwetten-news\/fenerbahce-mit-rekordtransfer-top-torjaeger-der-ligue-1-kommt\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fenerbahce mit Rekordtransfer: Top-Torj\u00e4ger der Ligue 1 kommt\" \/>\n<meta property=\"og:description\" content=\"Der franz\u00f6sische Torsch\u00fctzenk\u00f6nig wechselt f\u00fcr 39 Millionen Euro von Marseille zu Fenerbahce \u2013 welche Rekorde der Deal in der T\u00fcrkei bricht.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tipico.de\/wett-tipps\/sportwetten-news\/fenerbahce-mit-rekordtransfer-top-torjaeger-der-ligue-1-kommt\" \/>\n<meta property=\"og:site_name\" content=\"Tipico Wett Tipps\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tipico\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-15T12:07:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tipico.de\/wett-tipps\/wp-content\/uploads\/2024\/11\/fenerbahce-Fans.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Matthias Schmied\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Tipico_de\" \/>\n<meta name=\"twitter:site\" content=\"@Tipico_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Matthias Schmied\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/www.tipico.de\\\/wett-tipps\\\/sportwetten-news\\\/fenerbahce-mit-rekordtransfer-top-torjaeger-der-ligue-1-kommt#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tipico.de\\\/wett-tipps\\\/sportwetten-news\\\/fenerbahce-mit-rekordtransfer-top-torjaeger-der-ligue-1-kommt\"},\"author\":{\"name\":\"Matthias Schmied\",\"@id\":\"https:\\\/\\\/www.tipico.de\\\/wett-tipps\\\/#\\\/schema\\\/person\\\/55da74069990e12cea68c4d62025ae67\"},\"headline\":\"Fenerbahce mit Rekordtransfer: Top-Torj\u00e4ger der Ligue 1 kommt\",\"datePublished\":\"2026-07-15T12:07:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tipico.de\\\/wett-tipps\\\/sportwetten-news\\\/fenerbahce-mit-rekordtransfer-top-torjaeger-der-ligue-1-kommt\"},\"wordCount\":453,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tipico.de\\\/wett-tipps\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tipico.de\\\/wett-tipps\\\/sportwetten-news\\\/fenerbahce-mit-rekordtransfer-top-torjaeger-der-ligue-1-kommt#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tipico.de\\\/wett-tipps\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/fenerbahce-Fans.jpg\",\"inLanguage\":\"de\",\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tipico.de\\\/wett-tipps\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tipico.de\\\/wett-tipps\\\/sportwetten-news\\\/fenerbahce-mit-rekordtransfer-top-torjaeger-der-ligue-1-kommt\",\"url\":\"https:\\\/\\\/www.tipico.de\\\/wett-tipps\\\/sportwetten-news\\\/fenerbahce-mit-rekordtransfer-top-torjaeger-der-ligue-1-kommt\",\"name\":\"Fenerbahce mit Rekordtransfer: Top-Torj\u00e4ger der Ligue 1 kommt\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tipico.de\\\/wett-tipps\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tipico.de\\\/wett-tipps\\\/sportwetten-news\\\/fenerbahce-mit-rekordtransfer-top-torjaeger-der-ligue-1-kommt#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tipico.de\\\/wett-tipps\\\/sportwetten-news\\\/fenerbahce-mit-rekordtransfer-top-torjaeger-der-ligue-1-kommt#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tipico.de\\\/wett-tipps\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/fenerbahce-Fans.jpg\",\"datePublished\":\"2026-07-15T12:07:43+00:00\",\"description\":\"Der franz\u00f6sische Torsch\u00fctzenk\u00f6nig wechselt f\u00fcr 39 Millionen Euro von Marseille zu Fenerbahce \u2013 welche Rekorde der Deal in der T\u00fcrkei bricht.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tipico.de\\\/wett-tipps\\\/sportwetten-news\\\/fenerbahce-mit-rekordtransfer-top-torjaeger-der-ligue-1-kommt#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tipico.de\\\/wett-tipps\\\/sportwetten-news\\\/fenerbahce-mit-rekordtransfer-top-torjaeger-der-ligue-1-kommt\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.tipico.de\\\/wett-tipps\\\/sportwetten-news\\\/fenerbahce-mit-rekordtransfer-top-torjaeger-der-ligue-1-kommt#primaryimage\",\"url\":\"https:\\\/\\\/www.tipico.de\\\/wett-tipps\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/fenerbahce-Fans.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tipico.de\\\/wett-tipps\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/fenerbahce-Fans.jpg\",\"width\":1200,\"height\":800,\"caption\":\"ISTANBUL - Fenerbahce AS supporters prior to the Turkish Superlig match between Fenerbahce AS and Galatasaray SK at the Ulker stadium on Sept. 21, 2024 in Istanbul, Turkey. ANP Hollandse Hoogte Turkish Superlig 2024\\\/25 xVIxANPxSportx\\\/xGerritxvanxKeulenxIVx 509026806 originalFilename: 509026806.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tipico.de\\\/wett-tipps\\\/sportwetten-news\\\/fenerbahce-mit-rekordtransfer-top-torjaeger-der-ligue-1-kommt#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Start\",\"item\":\"https:\\\/\\\/www.tipico.de\\\/wett-tipps\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fu\u00dfball heute\",\"item\":\"https:\\\/\\\/www.tipico.de\\\/wett-tipps\\\/sportwetten-news\\\/category\\\/fussball-heute\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Fenerbahce mit Rekordtransfer: Top-Torj\u00e4ger der Ligue 1 kommt\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tipico.de\\\/wett-tipps\\\/#website\",\"url\":\"https:\\\/\\\/www.tipico.de\\\/wett-tipps\\\/\",\"name\":\"Tipico Wett Tipps\",\"description\":\"Wett Tipps heute &amp; aktuelle Sportwetten News\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tipico.de\\\/wett-tipps\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tipico.de\\\/wett-tipps\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.tipico.de\\\/wett-tipps\\\/#organization\",\"name\":\"Tipico\",\"url\":\"https:\\\/\\\/www.tipico.de\\\/wett-tipps\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.tipico.de\\\/wett-tipps\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.tipico.de\\\/wett-tipps\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/www.tipico.de\\\/wett-tipps\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/logo.svg\",\"width\":\"1024\",\"height\":\"1024\",\"caption\":\"Tipico\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tipico.de\\\/wett-tipps\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/tipico\\\/\",\"https:\\\/\\\/x.com\\\/Tipico_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tipico.de\\\/wett-tipps\\\/#\\\/schema\\\/person\\\/55da74069990e12cea68c4d62025ae67\",\"name\":\"Matthias Schmied\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c51cb430a4089ff0695b45e0a8193ecfce86c903f44c87bd440bf17bce7d42e6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c51cb430a4089ff0695b45e0a8193ecfce86c903f44c87bd440bf17bce7d42e6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c51cb430a4089ff0695b45e0a8193ecfce86c903f44c87bd440bf17bce7d42e6?s=96&d=mm&r=g\",\"caption\":\"Matthias Schmied\"},\"description\":\"Matthias schreibt f\u00fcr den Sport-Blog \u00fcber zahlreiche internationale Top-Sportarten. Sein Schwerpunkt liegt auf Fu\u00dfball \u2013 insbesondere auf Borussia Dortmund, der Serie A, La Liga sowie dem DFB-Team. Dar\u00fcber hinaus berichtet er regelm\u00e4\u00dfig \u00fcber Tennis, Handball, Darts, Eishockey, Basketball, Baseball, Radsport und gro\u00dfe Boxk\u00e4mpfe \u2013 unter anderem \u00fcber Wettbewerbe wie die Handball-Bundesliga, die NHL, die BBL und die Tour de France. Bei seinen Analysen legt Matthias besonderen Wert auf Statistiken und Daten. Auf dieser Basis erstellt er fundierte Analysen, Prognosen und Wett-Tipps zu den wichtigsten Spielen und Events.\",\"url\":\"https:\\\/\\\/www.tipico.de\\\/wett-tipps\\\/author\\\/matthias-schmied\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Fenerbahce mit Rekordtransfer: Top-Torj\u00e4ger der Ligue 1 kommt","description":"Der franz\u00f6sische Torsch\u00fctzenk\u00f6nig wechselt f\u00fcr 39 Millionen Euro von Marseille zu Fenerbahce \u2013 welche Rekorde der Deal in der T\u00fcrkei bricht.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tipico.de\/wett-tipps\/sportwetten-news\/fenerbahce-mit-rekordtransfer-top-torjaeger-der-ligue-1-kommt","og_locale":"de_DE","og_type":"article","og_title":"Fenerbahce mit Rekordtransfer: Top-Torj\u00e4ger der Ligue 1 kommt","og_description":"Der franz\u00f6sische Torsch\u00fctzenk\u00f6nig wechselt f\u00fcr 39 Millionen Euro von Marseille zu Fenerbahce \u2013 welche Rekorde der Deal in der T\u00fcrkei bricht.","og_url":"https:\/\/www.tipico.de\/wett-tipps\/sportwetten-news\/fenerbahce-mit-rekordtransfer-top-torjaeger-der-ligue-1-kommt","og_site_name":"Tipico Wett Tipps","article_publisher":"https:\/\/www.facebook.com\/tipico\/","article_published_time":"2026-07-15T12:07:43+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/www.tipico.de\/wett-tipps\/wp-content\/uploads\/2024\/11\/fenerbahce-Fans.jpg","type":"image\/jpeg"}],"author":"Matthias Schmied","twitter_card":"summary_large_image","twitter_creator":"@Tipico_de","twitter_site":"@Tipico_de","twitter_misc":{"Verfasst von":"Matthias Schmied","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.tipico.de\/wett-tipps\/sportwetten-news\/fenerbahce-mit-rekordtransfer-top-torjaeger-der-ligue-1-kommt#article","isPartOf":{"@id":"https:\/\/www.tipico.de\/wett-tipps\/sportwetten-news\/fenerbahce-mit-rekordtransfer-top-torjaeger-der-ligue-1-kommt"},"author":{"name":"Matthias Schmied","@id":"https:\/\/www.tipico.de\/wett-tipps\/#\/schema\/person\/55da74069990e12cea68c4d62025ae67"},"headline":"Fenerbahce mit Rekordtransfer: Top-Torj\u00e4ger der Ligue 1 kommt","datePublished":"2026-07-15T12:07:43+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tipico.de\/wett-tipps\/sportwetten-news\/fenerbahce-mit-rekordtransfer-top-torjaeger-der-ligue-1-kommt"},"wordCount":453,"publisher":{"@id":"https:\/\/www.tipico.de\/wett-tipps\/#organization"},"image":{"@id":"https:\/\/www.tipico.de\/wett-tipps\/sportwetten-news\/fenerbahce-mit-rekordtransfer-top-torjaeger-der-ligue-1-kommt#primaryimage"},"thumbnailUrl":"https:\/\/www.tipico.de\/wett-tipps\/wp-content\/uploads\/2024\/11\/fenerbahce-Fans.jpg","inLanguage":"de","copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/www.tipico.de\/wett-tipps\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tipico.de\/wett-tipps\/sportwetten-news\/fenerbahce-mit-rekordtransfer-top-torjaeger-der-ligue-1-kommt","url":"https:\/\/www.tipico.de\/wett-tipps\/sportwetten-news\/fenerbahce-mit-rekordtransfer-top-torjaeger-der-ligue-1-kommt","name":"Fenerbahce mit Rekordtransfer: Top-Torj\u00e4ger der Ligue 1 kommt","isPartOf":{"@id":"https:\/\/www.tipico.de\/wett-tipps\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tipico.de\/wett-tipps\/sportwetten-news\/fenerbahce-mit-rekordtransfer-top-torjaeger-der-ligue-1-kommt#primaryimage"},"image":{"@id":"https:\/\/www.tipico.de\/wett-tipps\/sportwetten-news\/fenerbahce-mit-rekordtransfer-top-torjaeger-der-ligue-1-kommt#primaryimage"},"thumbnailUrl":"https:\/\/www.tipico.de\/wett-tipps\/wp-content\/uploads\/2024\/11\/fenerbahce-Fans.jpg","datePublished":"2026-07-15T12:07:43+00:00","description":"Der franz\u00f6sische Torsch\u00fctzenk\u00f6nig wechselt f\u00fcr 39 Millionen Euro von Marseille zu Fenerbahce \u2013 welche Rekorde der Deal in der T\u00fcrkei bricht.","breadcrumb":{"@id":"https:\/\/www.tipico.de\/wett-tipps\/sportwetten-news\/fenerbahce-mit-rekordtransfer-top-torjaeger-der-ligue-1-kommt#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tipico.de\/wett-tipps\/sportwetten-news\/fenerbahce-mit-rekordtransfer-top-torjaeger-der-ligue-1-kommt"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.tipico.de\/wett-tipps\/sportwetten-news\/fenerbahce-mit-rekordtransfer-top-torjaeger-der-ligue-1-kommt#primaryimage","url":"https:\/\/www.tipico.de\/wett-tipps\/wp-content\/uploads\/2024\/11\/fenerbahce-Fans.jpg","contentUrl":"https:\/\/www.tipico.de\/wett-tipps\/wp-content\/uploads\/2024\/11\/fenerbahce-Fans.jpg","width":1200,"height":800,"caption":"ISTANBUL - Fenerbahce AS supporters prior to the Turkish Superlig match between Fenerbahce AS and Galatasaray SK at the Ulker stadium on Sept. 21, 2024 in Istanbul, Turkey. ANP Hollandse Hoogte Turkish Superlig 2024\/25 xVIxANPxSportx\/xGerritxvanxKeulenxIVx 509026806 originalFilename: 509026806.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tipico.de\/wett-tipps\/sportwetten-news\/fenerbahce-mit-rekordtransfer-top-torjaeger-der-ligue-1-kommt#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Start","item":"https:\/\/www.tipico.de\/wett-tipps\/"},{"@type":"ListItem","position":2,"name":"Fu\u00dfball heute","item":"https:\/\/www.tipico.de\/wett-tipps\/sportwetten-news\/category\/fussball-heute"},{"@type":"ListItem","position":3,"name":"Fenerbahce mit Rekordtransfer: Top-Torj\u00e4ger der Ligue 1 kommt"}]},{"@type":"WebSite","@id":"https:\/\/www.tipico.de\/wett-tipps\/#website","url":"https:\/\/www.tipico.de\/wett-tipps\/","name":"Tipico Wett Tipps","description":"Wett Tipps heute &amp; aktuelle Sportwetten News","publisher":{"@id":"https:\/\/www.tipico.de\/wett-tipps\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tipico.de\/wett-tipps\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.tipico.de\/wett-tipps\/#organization","name":"Tipico","url":"https:\/\/www.tipico.de\/wett-tipps\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.tipico.de\/wett-tipps\/#\/schema\/logo\/image\/","url":"https:\/\/www.tipico.de\/wett-tipps\/wp-content\/uploads\/2021\/02\/logo.svg","contentUrl":"https:\/\/www.tipico.de\/wett-tipps\/wp-content\/uploads\/2021\/02\/logo.svg","width":"1024","height":"1024","caption":"Tipico"},"image":{"@id":"https:\/\/www.tipico.de\/wett-tipps\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/tipico\/","https:\/\/x.com\/Tipico_de"]},{"@type":"Person","@id":"https:\/\/www.tipico.de\/wett-tipps\/#\/schema\/person\/55da74069990e12cea68c4d62025ae67","name":"Matthias Schmied","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/c51cb430a4089ff0695b45e0a8193ecfce86c903f44c87bd440bf17bce7d42e6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c51cb430a4089ff0695b45e0a8193ecfce86c903f44c87bd440bf17bce7d42e6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c51cb430a4089ff0695b45e0a8193ecfce86c903f44c87bd440bf17bce7d42e6?s=96&d=mm&r=g","caption":"Matthias Schmied"},"description":"Matthias schreibt f\u00fcr den Sport-Blog \u00fcber zahlreiche internationale Top-Sportarten. Sein Schwerpunkt liegt auf Fu\u00dfball \u2013 insbesondere auf Borussia Dortmund, der Serie A, La Liga sowie dem DFB-Team. Dar\u00fcber hinaus berichtet er regelm\u00e4\u00dfig \u00fcber Tennis, Handball, Darts, Eishockey, Basketball, Baseball, Radsport und gro\u00dfe Boxk\u00e4mpfe \u2013 unter anderem \u00fcber Wettbewerbe wie die Handball-Bundesliga, die NHL, die BBL und die Tour de France. Bei seinen Analysen legt Matthias besonderen Wert auf Statistiken und Daten. Auf dieser Basis erstellt er fundierte Analysen, Prognosen und Wett-Tipps zu den wichtigsten Spielen und Events.","url":"https:\/\/www.tipico.de\/wett-tipps\/author\/matthias-schmied"}]}},"_links":{"self":[{"href":"https:\/\/www.tipico.de\/wett-tipps\/wp-json\/wp\/v2\/posts\/482366","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tipico.de\/wett-tipps\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tipico.de\/wett-tipps\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tipico.de\/wett-tipps\/wp-json\/wp\/v2\/users\/110"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tipico.de\/wett-tipps\/wp-json\/wp\/v2\/comments?post=482366"}],"version-history":[{"count":1,"href":"https:\/\/www.tipico.de\/wett-tipps\/wp-json\/wp\/v2\/posts\/482366\/revisions"}],"predecessor-version":[{"id":482367,"href":"https:\/\/www.tipico.de\/wett-tipps\/wp-json\/wp\/v2\/posts\/482366\/revisions\/482367"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tipico.de\/wett-tipps\/wp-json\/wp\/v2\/media\/263691"}],"wp:attachment":[{"href":"https:\/\/www.tipico.de\/wett-tipps\/wp-json\/wp\/v2\/media?parent=482366"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tipico.de\/wett-tipps\/wp-json\/wp\/v2\/tags?post=482366"},{"taxonomy":"news-category","embeddable":true,"href":"https:\/\/www.tipico.de\/wett-tipps\/wp-json\/wp\/v2\/news-category?post=482366"},{"taxonomy":"sport-news","embeddable":true,"href":"https:\/\/www.tipico.de\/wett-tipps\/wp-json\/wp\/v2\/sport-news?post=482366"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}